{"id":8192,"date":"2019-01-11T07:22:59","date_gmt":"2019-01-11T07:22:59","guid":{"rendered":"https:\/\/shinetheme.com\/travelerdata\/tour\/?page_id=8192"},"modified":"2021-07-12T11:16:31","modified_gmt":"2021-07-12T11:16:31","slug":"sidebar-search-layout","status":"publish","type":"page","link":"https:\/\/dreamlifetravel.gr\/fr\/sidebar-search-layout\/","title":{"rendered":"Disposition de la recherche dans la barre lat\u00e9rale"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":8301,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-tour-search.php","meta":{"footnotes":""},"class_list":["post-8192","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sidebar Search Layout - Dream Life Travel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dreamlifetravel.gr\/fr\/sidebar-search-layout\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sidebar Search Layout - Dream Life Travel\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dreamlifetravel.gr\/fr\/sidebar-search-layout\/\" \/>\n<meta property=\"og:site_name\" content=\"Dream Life Travel\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Dream-life-travel-109893747993004\/?ref=pages_you_manage\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-12T11:16:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dreamlifetravel.gr\/wp-content\/uploads\/2014\/11\/Santorini-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dreamlifetravel.gr\\\/en\\\/sidebar-search-layout\\\/\",\"url\":\"https:\\\/\\\/dreamlifetravel.gr\\\/en\\\/sidebar-search-layout\\\/\",\"name\":\"Sidebar Search Layout - Dream Life Travel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dreamlifetravel.gr\\\/el\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dreamlifetravel.gr\\\/en\\\/sidebar-search-layout\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dreamlifetravel.gr\\\/en\\\/sidebar-search-layout\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dreamlifetravel.gr\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/Santorini-1.jpg\",\"datePublished\":\"2019-01-11T07:22:59+00:00\",\"dateModified\":\"2021-07-12T11:16:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dreamlifetravel.gr\\\/en\\\/sidebar-search-layout\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dreamlifetravel.gr\\\/en\\\/sidebar-search-layout\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dreamlifetravel.gr\\\/en\\\/sidebar-search-layout\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dreamlifetravel.gr\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/Santorini-1.jpg\",\"contentUrl\":\"https:\\\/\\\/dreamlifetravel.gr\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/Santorini-1.jpg\",\"width\":1920,\"height\":1200,\"caption\":\"Santorini\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dreamlifetravel.gr\\\/en\\\/sidebar-search-layout\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dreamlifetravel.gr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sidebar Search Layout\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dreamlifetravel.gr\\\/el\\\/#website\",\"url\":\"https:\\\/\\\/dreamlifetravel.gr\\\/el\\\/\",\"name\":\"Dream Life Travel\",\"description\":\"The Best Tour Experience\",\"publisher\":{\"@id\":\"https:\\\/\\\/dreamlifetravel.gr\\\/el\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dreamlifetravel.gr\\\/el\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dreamlifetravel.gr\\\/el\\\/#organization\",\"name\":\"dreamlifetravel\",\"url\":\"https:\\\/\\\/dreamlifetravel.gr\\\/el\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dreamlifetravel.gr\\\/el\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dreamlifetravel.gr\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/203377155_111002757790531_4475099207187108932_n-1-1.png\",\"contentUrl\":\"https:\\\/\\\/dreamlifetravel.gr\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/203377155_111002757790531_4475099207187108932_n-1-1.png\",\"width\":140,\"height\":57,\"caption\":\"dreamlifetravel\"},\"image\":{\"@id\":\"https:\\\/\\\/dreamlifetravel.gr\\\/el\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Dream-life-travel-109893747993004\\\/?ref=pages_you_manage\",\"https:\\\/\\\/www.instagram.com\\\/dreamlife_travel_\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sidebar Search Layout - Dream Life Travel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dreamlifetravel.gr\/fr\/sidebar-search-layout\/","og_locale":"fr_FR","og_type":"article","og_title":"Sidebar Search Layout - Dream Life Travel","og_url":"https:\/\/dreamlifetravel.gr\/fr\/sidebar-search-layout\/","og_site_name":"Dream Life Travel","article_publisher":"https:\/\/www.facebook.com\/Dream-life-travel-109893747993004\/?ref=pages_you_manage","article_modified_time":"2021-07-12T11:16:31+00:00","og_image":[{"width":1920,"height":1200,"url":"https:\/\/dreamlifetravel.gr\/wp-content\/uploads\/2014\/11\/Santorini-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dreamlifetravel.gr\/en\/sidebar-search-layout\/","url":"https:\/\/dreamlifetravel.gr\/en\/sidebar-search-layout\/","name":"Sidebar Search Layout - Dream Life Travel","isPartOf":{"@id":"https:\/\/dreamlifetravel.gr\/el\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dreamlifetravel.gr\/en\/sidebar-search-layout\/#primaryimage"},"image":{"@id":"https:\/\/dreamlifetravel.gr\/en\/sidebar-search-layout\/#primaryimage"},"thumbnailUrl":"https:\/\/dreamlifetravel.gr\/wp-content\/uploads\/2014\/11\/Santorini-1.jpg","datePublished":"2019-01-11T07:22:59+00:00","dateModified":"2021-07-12T11:16:31+00:00","breadcrumb":{"@id":"https:\/\/dreamlifetravel.gr\/en\/sidebar-search-layout\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dreamlifetravel.gr\/en\/sidebar-search-layout\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dreamlifetravel.gr\/en\/sidebar-search-layout\/#primaryimage","url":"https:\/\/dreamlifetravel.gr\/wp-content\/uploads\/2014\/11\/Santorini-1.jpg","contentUrl":"https:\/\/dreamlifetravel.gr\/wp-content\/uploads\/2014\/11\/Santorini-1.jpg","width":1920,"height":1200,"caption":"Santorini"},{"@type":"BreadcrumbList","@id":"https:\/\/dreamlifetravel.gr\/en\/sidebar-search-layout\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dreamlifetravel.gr\/"},{"@type":"ListItem","position":2,"name":"Sidebar Search Layout"}]},{"@type":"WebSite","@id":"https:\/\/dreamlifetravel.gr\/el\/#website","url":"https:\/\/dreamlifetravel.gr\/el\/","name":"Voyage de la vie de r\u00eave","description":"La meilleure exp\u00e9rience de visite","publisher":{"@id":"https:\/\/dreamlifetravel.gr\/el\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dreamlifetravel.gr\/el\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/dreamlifetravel.gr\/el\/#organization","name":"dreamlifetravel","url":"https:\/\/dreamlifetravel.gr\/el\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dreamlifetravel.gr\/el\/#\/schema\/logo\/image\/","url":"https:\/\/dreamlifetravel.gr\/wp-content\/uploads\/2018\/12\/203377155_111002757790531_4475099207187108932_n-1-1.png","contentUrl":"https:\/\/dreamlifetravel.gr\/wp-content\/uploads\/2018\/12\/203377155_111002757790531_4475099207187108932_n-1-1.png","width":140,"height":57,"caption":"dreamlifetravel"},"image":{"@id":"https:\/\/dreamlifetravel.gr\/el\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Dream-life-travel-109893747993004\/?ref=pages_you_manage","https:\/\/www.instagram.com\/dreamlife_travel_\/"]}]}},"_links":{"self":[{"href":"https:\/\/dreamlifetravel.gr\/fr\/wp-json\/wp\/v2\/pages\/8192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dreamlifetravel.gr\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dreamlifetravel.gr\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dreamlifetravel.gr\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dreamlifetravel.gr\/fr\/wp-json\/wp\/v2\/comments?post=8192"}],"version-history":[{"count":1,"href":"https:\/\/dreamlifetravel.gr\/fr\/wp-json\/wp\/v2\/pages\/8192\/revisions"}],"predecessor-version":[{"id":8194,"href":"https:\/\/dreamlifetravel.gr\/fr\/wp-json\/wp\/v2\/pages\/8192\/revisions\/8194"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dreamlifetravel.gr\/fr\/wp-json\/wp\/v2\/media\/8301"}],"wp:attachment":[{"href":"https:\/\/dreamlifetravel.gr\/fr\/wp-json\/wp\/v2\/media?parent=8192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}